{"id":41,"count":0,"description":"","link":"https:\/\/atormentador.com.br\/en\/tag\/cabeca-de-alien\/","name":"cabe\u00e7a de alien","slug":"cabeca-de-alien","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arquivo de cabe\u00e7a de alien - Atormentador - Contos Originais, Terror, Horror e Fic\u00e7\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/atormentador.com.br\/en\/tag\/cabeca-de-alien\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de cabe\u00e7a de alien - Atormentador - Contos Originais, Terror, Horror e Fic\u00e7\u00e3o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/atormentador.com.br\/en\/tag\/cabeca-de-alien\/\" \/>\n<meta property=\"og:site_name\" content=\"Atormentador - Contos Originais, Terror, Horror e Fic\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/atormentador.com.br\/tag\/cabeca-de-alien\/\",\"url\":\"https:\/\/atormentador.com.br\/tag\/cabeca-de-alien\/\",\"name\":\"Arquivo de cabe\u00e7a de alien - Atormentador - Contos Originais, Terror, Horror e Fic\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\/\/atormentador.com.br\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/atormentador.com.br\/tag\/cabeca-de-alien\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/atormentador.com.br\/tag\/cabeca-de-alien\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/atormentador.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"cabe\u00e7a de alien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/atormentador.com.br\/#website\",\"url\":\"https:\/\/atormentador.com.br\/\",\"name\":\"Atormentador - Contos Originais, Terror, Horror e Fic\u00e7\u00e3o Cient\u00edfica, Sci-Fi\",\"description\":\"Contos Originais, Terror, Horror e Fic\u00e7\u00e3o\",\"publisher\":{\"@id\":\"https:\/\/atormentador.com.br\/#\/schema\/person\/24945385e2b6dd028cf5c6ce53497a7e\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/atormentador.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/atormentador.com.br\/#\/schema\/person\/24945385e2b6dd028cf5c6ce53497a7e\",\"name\":\"rene\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/atormentador.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/atormentador.com.br\/wp-content\/uploads\/2019\/10\/cropped-cropped-logo_atormentador.png\",\"contentUrl\":\"https:\/\/atormentador.com.br\/wp-content\/uploads\/2019\/10\/cropped-cropped-logo_atormentador.png\",\"width\":267,\"height\":90,\"caption\":\"rene\"},\"logo\":{\"@id\":\"https:\/\/atormentador.com.br\/#\/schema\/person\/image\/\"},\"description\":\"Profissional na \u00e1rea de TI sempre tive como hobby escrever contos.\",\"sameAs\":[\"http:\/\/www.atormentador.com.br\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de cabe\u00e7a de alien - Atormentador - Contos Originais, Terror, Horror e Fic\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/atormentador.com.br\/en\/tag\/cabeca-de-alien\/","og_locale":"en_US","og_type":"article","og_title":"Arquivo de cabe\u00e7a de alien - Atormentador - Contos Originais, Terror, Horror e Fic\u00e7\u00e3o","og_url":"https:\/\/atormentador.com.br\/en\/tag\/cabeca-de-alien\/","og_site_name":"Atormentador - Contos Originais, Terror, Horror e Fic\u00e7\u00e3o","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/atormentador.com.br\/tag\/cabeca-de-alien\/","url":"https:\/\/atormentador.com.br\/tag\/cabeca-de-alien\/","name":"Arquivo de cabe\u00e7a de alien - Atormentador - Contos Originais, Terror, Horror e Fic\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/atormentador.com.br\/#website"},"breadcrumb":{"@id":"https:\/\/atormentador.com.br\/tag\/cabeca-de-alien\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/atormentador.com.br\/tag\/cabeca-de-alien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/atormentador.com.br\/"},{"@type":"ListItem","position":2,"name":"cabe\u00e7a de alien"}]},{"@type":"WebSite","@id":"https:\/\/atormentador.com.br\/#website","url":"https:\/\/atormentador.com.br\/","name":"Atormentador - Contos Originais, Terror, Horror e Fic\u00e7\u00e3o Cient\u00edfica, Sci-Fi","description":"Contos Originais, Terror, Horror e Fic\u00e7\u00e3o","publisher":{"@id":"https:\/\/atormentador.com.br\/#\/schema\/person\/24945385e2b6dd028cf5c6ce53497a7e"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/atormentador.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/atormentador.com.br\/#\/schema\/person\/24945385e2b6dd028cf5c6ce53497a7e","name":"rene","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/atormentador.com.br\/#\/schema\/person\/image\/","url":"https:\/\/atormentador.com.br\/wp-content\/uploads\/2019\/10\/cropped-cropped-logo_atormentador.png","contentUrl":"https:\/\/atormentador.com.br\/wp-content\/uploads\/2019\/10\/cropped-cropped-logo_atormentador.png","width":267,"height":90,"caption":"rene"},"logo":{"@id":"https:\/\/atormentador.com.br\/#\/schema\/person\/image\/"},"description":"Profissional na \u00e1rea de TI sempre tive como hobby escrever contos.","sameAs":["http:\/\/www.atormentador.com.br"]}]}},"_links":{"self":[{"href":"https:\/\/atormentador.com.br\/en\/wp-json\/wp\/v2\/tags\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atormentador.com.br\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/atormentador.com.br\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/atormentador.com.br\/en\/wp-json\/wp\/v2\/posts?tags=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}